{"id":23753,"date":"2026-04-30T23:10:00","date_gmt":"2026-05-01T03:10:00","guid":{"rendered":"https:\/\/iwantmyhealthback.com\/le-coin-du-fondateur-edition-13-le-proces-en-double-aveugle\/"},"modified":"2026-05-13T09:54:32","modified_gmt":"2026-05-13T13:54:32","slug":"le-coin-du-fondateur-edition-13-le-proces-en-double-aveugle","status":"publish","type":"post","link":"https:\/\/iwantmyhealthback.com\/fr\/le-coin-du-fondateur-edition-13-le-proces-en-double-aveugle\/","title":{"rendered":"Le coin du fondateur Edition 13 : Le proc\u00e8s en double aveugle"},"content":{"rendered":"\n<p>L&rsquo;essai en double aveugle est au c\u0153ur des tests effectu\u00e9s par les entreprises pharmaceutiques. Il est d\u00e9sormais accept\u00e9 comme base d&rsquo;\u00e9valuation de l&rsquo;efficacit\u00e9 des produits. Cependant, fournit-il r\u00e9ellement l&rsquo;\u00e9talon-or de la confiance dont il est cr\u00e9dit\u00e9 ?  <\/p>\n<p>Le Dr Raghavan, concepteur de NANO SOMA\u00ae et homme ayant fait carri\u00e8re dans l&rsquo;industrie pharmaceutique, ne lui accorde pas le m\u00eame cr\u00e9dit que Big Pharma.<\/p>\n<p>La raison en est expliqu\u00e9e dans cet article de la revue <em>Nature<\/em> &#8211;<a href=\"https:\/\/nature.thenanosoma.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/nature.thenanosoma.com\/.<\/a><\/p>\n<p>L&rsquo;auteur, Nicholas Schork, affirme que les essais traditionnels ne donnent pas les r\u00e9sultats escompt\u00e9s, notamment en raison de la variabilit\u00e9 du profil physique du public, y compris des variables g\u00e9n\u00e9tiques et raciales, alors que les essais ont tendance \u00e0 \u00eatre men\u00e9s sur des personnes ayant un profil commun, comme les Blancs. Il en r\u00e9sulte que pour chaque personne que le m\u00e9dicament peut aider, il peut y en avoir jusqu&rsquo;\u00e0 24 pour lesquelles il ne pr\u00e9sente aucun avantage. C&rsquo;est en partie pour cette raison que les m\u00e9decins testent souvent plusieurs traitements afin de d\u00e9terminer celui qui convient le mieux \u00e0 un patient. Comme le dit Raghu, si l&rsquo;un des m\u00e9dicaments contre la tension art\u00e9rielle \u00e9tait vraiment efficace, les autres feraient faillite.   <\/p>\n<p>Une autre solution consiste \u00e0 r\u00e9aliser des essais N sur 1, dont la forme la plus simple est le t\u00e9moignage personnel : des personnes partagent leur exp\u00e9rience avec d&rsquo;autres, confirmant ainsi l&rsquo;efficacit\u00e9 du produit.<\/p>\n<p>L&rsquo;industrie pharmaceutique a \u00e9galement tout int\u00e9r\u00eat \u00e0 maintenir la proc\u00e9dure d&rsquo;essai accept\u00e9e, car les co\u00fbts li\u00e9s \u00e0 la proc\u00e9dure en double aveugle constituent une s\u00e9rieuse barri\u00e8re \u00e0 l&rsquo;entr\u00e9e pour les solutions alternatives. Peu de gens savent que l&rsquo;industrie pharmaceutique a v\u00e9ritablement d\u00e9but\u00e9 lorsque John D. Rockefeller, c\u00e9l\u00e8bre pour la Standard Oil, a d\u00e9couvert en Allemagne les premiers produits pharmaceutiques fabriqu\u00e9s \u00e0 partir de sables bitumineux, un d\u00e9chet du raffinage du p\u00e9trole, ce qui l&rsquo;a amen\u00e9 \u00e0 cr\u00e9er la m\u00e9decine occidentale (allopathique) et \u00e0 en faire sa force de vente. L&rsquo;essai en double aveugle est apparu avec l&rsquo;industrie alors que l&rsquo;humanit\u00e9 s&rsquo;\u00e9loignait des solutions naturelles de gu\u00e9rison pour se tourner vers les produits chimiques fabriqu\u00e9s par l&rsquo;homme.  <\/p>\n<p>\u00c0 mon avis, notre engagement dans les m\u00e9decines non naturelles s&rsquo;av\u00e9rera \u00eatre une phase passag\u00e8re, car nous reviendrons \u00e0 des solutions naturelles, tout comme nous le ferons pour l&rsquo;agriculture.<\/p>\n\n\t<section class=\"section\" id=\"section_37941398\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-701629972\">\n\n\n\t<div id=\"col-814780293\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2751215263\" class=\"text\">\n\t\t\n\n<p>\u00cates-vous pr\u00eat \u00e0 voir ce qu&rsquo;il peut faire pour vous ?<\/p>\n<p style=\"font-size:80%\">Appuyez sur le bouton ci-dessous et d\u00e9couvrez comment vous pouvez le faire !<\/p>\n\t\t\n<style>\n#text-2751215263 {\n  font-size: 1.55rem;\n  line-height: 1.4;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-2751215263 {\n    font-size: 1.65rem;\n    line-height: 0.75;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/iwantmyhealthback.com\/fr\/acheter\/\" target=\"_blank\" class=\"button primary is-large\" rel=\"noopener\" style=\"border-radius:10px;\">\n\t\t<span>J&#039;AI ENVIE D&#039;ESSAYER !<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1791139687\">\n\n\n\t<div id=\"col-698093036\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:#767676;border-width:2px 2px 2px 2px;\">\n\t<\/div>\n\t\t\t\n\n\t<div id=\"text-4281354656\" class=\"text\">\n\t\t\n\n<p><strong>*Ces d\u00e9clarations n&rsquo;ont pas \u00e9t\u00e9 \u00e9valu\u00e9es par la Food and Drug Administration des \u00c9tats-Unis. Ce produit n&rsquo;est pas destin\u00e9 \u00e0 diagnostiquer ou \u00e0 prescrire une quelconque condition m\u00e9dicale, ni \u00e0 pr\u00e9venir, traiter, att\u00e9nuer ou gu\u00e9rir une telle condition. Si vous souffrez d&rsquo;une maladie ou d&rsquo;un probl\u00e8me m\u00e9dical, consultez votre fournisseur de soins de sant\u00e9.  <\/strong><\/p>\n\t\t\n<style>\n#text-4281354656 {\n  font-size: 0.9rem;\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-698093036 > .col-inner {\n  padding: 10px 20px 5px 20px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_37941398 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_37941398 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;essai en double aveugle est au c\u0153ur des tests effectu\u00e9s par les entreprises pharmaceutiques. Il est d\u00e9sormais accept\u00e9 comme base d&rsquo;\u00e9valuation de l&rsquo;efficacit\u00e9 des produits. Cependant, fournit-il r\u00e9ellement l&rsquo;\u00e9talon-or de la confiance dont il est cr\u00e9dit\u00e9 ?  <\/p>\n","protected":false},"author":2,"featured_media":23287,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"bwfblock_default_font":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[34],"tags":[3495,3494,175,3493],"class_list":["post-23753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-essais-en-double-aveugle","tag-industrie-pharmaceutique","tag-nano-soma-fr","tag-temoignages-personnels"],"uagb_featured_image_src":{"full":["https:\/\/iwantmyhealthback.com\/wp-content\/uploads\/2026\/04\/The-Founders-Corner-Edition-13-The-Double-blind-Trial.jpg",1920,1080,false],"thumbnail":["https:\/\/iwantmyhealthback.com\/wp-content\/uploads\/2026\/04\/The-Founders-Corner-Edition-13-The-Double-blind-Trial-150x150.jpg",150,150,true],"medium":["https:\/\/iwantmyhealthback.com\/wp-content\/uploads\/2026\/04\/The-Founders-Corner-Edition-13-The-Double-blind-Trial-300x169.jpg",300,169,true],"medium_large":["https:\/\/iwantmyhealthback.com\/wp-content\/uploads\/2026\/04\/The-Founders-Corner-Edition-13-The-Double-blind-Trial-768x432.jpg",768,432,true],"large":["https:\/\/iwantmyhealthback.com\/wp-content\/uploads\/2026\/04\/The-Founders-Corner-Edition-13-The-Double-blind-Trial-1024x576.jpg",1020,574,true],"1536x1536":["https:\/\/iwantmyhealthback.com\/wp-content\/uploads\/2026\/04\/The-Founders-Corner-Edition-13-The-Double-blind-Trial-1536x864.jpg",1536,864,true],"2048x2048":["https:\/\/iwantmyhealthback.com\/wp-content\/uploads\/2026\/04\/The-Founders-Corner-Edition-13-The-Double-blind-Trial.jpg",1920,1080,false],"woocommerce_thumbnail":["https:\/\/iwantmyhealthback.com\/wp-content\/uploads\/2026\/04\/The-Founders-Corner-Edition-13-The-Double-blind-Trial-300x169.jpg",300,169,true],"woocommerce_single":["https:\/\/iwantmyhealthback.com\/wp-content\/uploads\/2026\/04\/The-Founders-Corner-Edition-13-The-Double-blind-Trial-510x287.jpg",510,287,true],"woocommerce_gallery_thumbnail":["https:\/\/iwantmyhealthback.com\/wp-content\/uploads\/2026\/04\/The-Founders-Corner-Edition-13-The-Double-blind-Trial-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"IWantMyHealthBack","author_link":"https:\/\/iwantmyhealthback.com\/fr\/author\/anthonette\/"},"uagb_comment_info":0,"uagb_excerpt":"L'essai en double aveugle est au c\u0153ur des tests effectu\u00e9s par les entreprises pharmaceutiques. Il est d\u00e9sormais accept\u00e9 comme base d'\u00e9valuation de l'efficacit\u00e9 des produits. Cependant, fournit-il r\u00e9ellement l'\u00e9talon-or de la confiance dont il est cr\u00e9dit\u00e9 ?","_links":{"self":[{"href":"https:\/\/iwantmyhealthback.com\/fr\/wp-json\/wp\/v2\/posts\/23753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iwantmyhealthback.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iwantmyhealthback.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iwantmyhealthback.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/iwantmyhealthback.com\/fr\/wp-json\/wp\/v2\/comments?post=23753"}],"version-history":[{"count":0,"href":"https:\/\/iwantmyhealthback.com\/fr\/wp-json\/wp\/v2\/posts\/23753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iwantmyhealthback.com\/fr\/wp-json\/wp\/v2\/media\/23287"}],"wp:attachment":[{"href":"https:\/\/iwantmyhealthback.com\/fr\/wp-json\/wp\/v2\/media?parent=23753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iwantmyhealthback.com\/fr\/wp-json\/wp\/v2\/categories?post=23753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iwantmyhealthback.com\/fr\/wp-json\/wp\/v2\/tags?post=23753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}